{"id":969,"date":"2025-10-13T18:21:07","date_gmt":"2025-10-13T18:21:07","guid":{"rendered":"https:\/\/dev.gordis-genusswelt.com\/?page_id=969"},"modified":"2026-03-16T18:41:05","modified_gmt":"2026-03-16T18:41:05","slug":"neuigkeiten","status":"publish","type":"page","link":"https:\/\/gordis-genusswelt.com\/en\/neuigkeiten\/","title":{"rendered":"News"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"969\" class=\"elementor elementor-969\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6rqielb e-flex e-con-boxed e-con e-parent\" data-id=\"6rqielb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9d96fdd e-con-full e-flex e-con e-child\" data-id=\"9d96fdd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f250ef9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f250ef9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">News<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-590aubi e-flex e-con-boxed e-con e-parent\" data-id=\"590aubi\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e99a333 e-con-full e-flex e-con e-child\" data-id=\"e99a333\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80d7c7f elementor-widget elementor-widget-video\" data-id=\"80d7c7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/gordis-genusswelt.com\/wp-content\/uploads\/2025\/11\/WhatsApp-Video-2025-10-29-um-13.17.53_3acd4f4e.mp4\" controls=\"\" preload=\"metadata\" controlslist=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc640bf e-con-full e-flex e-con e-child\" data-id=\"bc640bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c89b1e elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"4c89b1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"> Food-Influencer Kevin Liebl zu Gordis Genusswelt<\/h3><p class=\"elementor-image-box-description\">aufgenommen auf der Offerta Karlsruhe 2025  <\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Neuigkeiten https:\/\/gordis-genusswelt.com\/wp-content\/uploads\/2025\/11\/WhatsApp-Video-2025-10-29-um-13.17.53_3acd4f4e.mp4 Food-Influencer Kevin Liebl zu Gordis Genusswelt aufgenommen auf der Offerta Karlsruhe 2025<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-969","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neuigkeiten \u2013 Gordis Genusswelt<\/title>\n<meta name=\"description\" content=\"Gordis Genusswelt Neuigkeiten: Hier finden Sie aktuelle Informationen zu Veranstaltungen, Messen, Kooperationen und neuen Entwicklungen rund um unsere Weine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gordis-genusswelt.com\/en\/neuigkeiten\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neuigkeiten \u2013 Gordis Genusswelt\" \/>\n<meta property=\"og:description\" content=\"Gordis Genusswelt Neuigkeiten: Hier finden Sie aktuelle Informationen zu Veranstaltungen, Messen, Kooperationen und neuen Entwicklungen rund um unsere Weine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gordis-genusswelt.com\/en\/neuigkeiten\/\" \/>\n<meta property=\"og:site_name\" content=\"Gordi&#039;s Genusswelt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-16T18:41:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gordis-genusswelt.com\\\/neuigkeiten\\\/\",\"url\":\"https:\\\/\\\/gordis-genusswelt.com\\\/neuigkeiten\\\/\",\"name\":\"Neuigkeiten \u2013 Gordis Genusswelt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gordis-genusswelt.com\\\/#website\"},\"datePublished\":\"2025-10-13T18:21:07+00:00\",\"dateModified\":\"2026-03-16T18:41:05+00:00\",\"description\":\"Gordis Genusswelt Neuigkeiten: Hier finden Sie aktuelle Informationen zu Veranstaltungen, Messen, Kooperationen und neuen Entwicklungen rund um unsere Weine.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gordis-genusswelt.com\\\/neuigkeiten\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gordis-genusswelt.com\\\/neuigkeiten\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gordis-genusswelt.com\\\/neuigkeiten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gordis-genusswelt.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neuigkeiten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gordis-genusswelt.com\\\/#website\",\"url\":\"https:\\\/\\\/gordis-genusswelt.com\\\/\",\"name\":\"Gordi's Genusswelt\",\"description\":\"Weinverkostungen, Events und besondere Weine\",\"publisher\":{\"@id\":\"https:\\\/\\\/gordis-genusswelt.com\\\/#organization\"},\"alternateName\":\"Gordis Genusswelt\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gordis-genusswelt.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gordis-genusswelt.com\\\/#organization\",\"name\":\"Gordi's Genusswelt\",\"url\":\"https:\\\/\\\/gordis-genusswelt.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gordis-genusswelt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gordis-genusswelt.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-cropped-logo-normal-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/gordis-genusswelt.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-cropped-logo-normal-scaled-1.png\",\"width\":2322,\"height\":2145,\"caption\":\"Gordi's Genusswelt\"},\"image\":{\"@id\":\"https:\\\/\\\/gordis-genusswelt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neuigkeiten \u2013 Gordis Genusswelt","description":"Gordis Genusswelt Neuigkeiten: Hier finden Sie aktuelle Informationen zu Veranstaltungen, Messen, Kooperationen und neuen Entwicklungen rund um unsere Weine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gordis-genusswelt.com\/en\/neuigkeiten\/","og_locale":"en_US","og_type":"article","og_title":"Neuigkeiten \u2013 Gordis Genusswelt","og_description":"Gordis Genusswelt Neuigkeiten: Hier finden Sie aktuelle Informationen zu Veranstaltungen, Messen, Kooperationen und neuen Entwicklungen rund um unsere Weine.","og_url":"https:\/\/gordis-genusswelt.com\/en\/neuigkeiten\/","og_site_name":"Gordi&#039;s Genusswelt","article_modified_time":"2026-03-16T18:41:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gordis-genusswelt.com\/neuigkeiten\/","url":"https:\/\/gordis-genusswelt.com\/neuigkeiten\/","name":"Neuigkeiten \u2013 Gordis Genusswelt","isPartOf":{"@id":"https:\/\/gordis-genusswelt.com\/#website"},"datePublished":"2025-10-13T18:21:07+00:00","dateModified":"2026-03-16T18:41:05+00:00","description":"Gordis Genusswelt Neuigkeiten: Hier finden Sie aktuelle Informationen zu Veranstaltungen, Messen, Kooperationen und neuen Entwicklungen rund um unsere Weine.","breadcrumb":{"@id":"https:\/\/gordis-genusswelt.com\/neuigkeiten\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gordis-genusswelt.com\/neuigkeiten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gordis-genusswelt.com\/neuigkeiten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gordis-genusswelt.com\/"},{"@type":"ListItem","position":2,"name":"Neuigkeiten"}]},{"@type":"WebSite","@id":"https:\/\/gordis-genusswelt.com\/#website","url":"https:\/\/gordis-genusswelt.com\/","name":"Gordi's Genusswelt","description":"Weinverkostungen, Events und besondere Weine","publisher":{"@id":"https:\/\/gordis-genusswelt.com\/#organization"},"alternateName":"Gordis Genusswelt","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gordis-genusswelt.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gordis-genusswelt.com\/#organization","name":"Gordi's Genusswelt","url":"https:\/\/gordis-genusswelt.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gordis-genusswelt.com\/#\/schema\/logo\/image\/","url":"https:\/\/gordis-genusswelt.com\/wp-content\/uploads\/2025\/08\/cropped-cropped-logo-normal-scaled-1.png","contentUrl":"https:\/\/gordis-genusswelt.com\/wp-content\/uploads\/2025\/08\/cropped-cropped-logo-normal-scaled-1.png","width":2322,"height":2145,"caption":"Gordi's Genusswelt"},"image":{"@id":"https:\/\/gordis-genusswelt.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gordis-genusswelt.com\/en\/wp-json\/wp\/v2\/pages\/969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gordis-genusswelt.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gordis-genusswelt.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gordis-genusswelt.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gordis-genusswelt.com\/en\/wp-json\/wp\/v2\/comments?post=969"}],"version-history":[{"count":55,"href":"https:\/\/gordis-genusswelt.com\/en\/wp-json\/wp\/v2\/pages\/969\/revisions"}],"predecessor-version":[{"id":1216,"href":"https:\/\/gordis-genusswelt.com\/en\/wp-json\/wp\/v2\/pages\/969\/revisions\/1216"}],"wp:attachment":[{"href":"https:\/\/gordis-genusswelt.com\/en\/wp-json\/wp\/v2\/media?parent=969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}